{"id":53724,"date":"2023-09-12T10:04:56","date_gmt":"2023-09-12T08:04:56","guid":{"rendered":"https:\/\/mf.ag\/?page_id=53724"},"modified":"2024-07-15T13:40:58","modified_gmt":"2024-07-15T11:40:58","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<p>Vielen Dank f\u00fcr Ihren Besuch auf unserer Webseite und f\u00fcr Ihr Interesse an unseren Dienstleistungen. Der Schutz Ihrer personenbezogenen Daten ist uns ein wichtiges Anliegen. Wir verarbeiten Ihre personenbezogenen Daten ausschlie\u00dflich im Rahmen des geltenden Datenschutzrechts; dies umfasst insbesondere die Bestimmungen der EU-Datenschutz-Grundverordnung (im Folgenden: \u201e<strong>DSGVO<\/strong>\u201c) sowie des \u00f6sterreichischen Datenschutzgesetzes (im Folgenden \u201e<strong>DSG<\/strong>\u201c). Nachfolgend m\u00f6chten wir Sie dar\u00fcber informieren, welche personenbezogenen Daten wir erheben und wie wir sie verarbeiten.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading is-style-default\" id=\"h-1-verantwortlicher\"><strong>\u00a7 1&nbsp;VERANTWORTLICHER&nbsp;&nbsp;<\/strong><\/h4>\n\n\n\n<p>Verantwortlicher f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten ist:&nbsp;<br>Management Factory Corporate Advisory GmbH&nbsp;&nbsp;<br>Lothringerstr. 14&nbsp;&nbsp;<br>1030 Wien&nbsp;<br>\u00d6STERREICH<br>E-Mail: office@mf.ag&nbsp;<\/p>\n\n\n\n<p>(im Folgenden auch \u201e<strong>Management Factory<\/strong>\u201c, \u201e<strong>wir<\/strong>\u201c, \u201e<strong>uns<\/strong>\u201c, \u201e<strong>unser<\/strong>\u201c genannt).&nbsp;<\/p>\n\n\n\n<p>Kontaktdaten unseres Datenschutzbeauftragten: <a href=\"https:\/\/mf.ag\/de\/christian-egger\/\">Mag. Christian Egger,<\/a> christian.egger@mf.ag<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 2&nbsp;<strong>DATENVERARBEITUNG UND DEREN ZWECKE<\/strong><\/strong><\/h4>\n\n\n\n<p>\u201e<strong>Personenbezogene Daten<\/strong>\u201c sind vereinfacht gesagt Informationen, die R\u00fcckschl\u00fcsse auf Ihre Person zulassen. Konkret werden darunter alle Informationen verstanden, die sich auf eine identifizierte (oder identifizierbare) nat\u00fcrliche Person beziehen. Darunter f\u00e4llt beispielsweise Ihr Name, Ihr Geburtsdatum, Ihre Anschrift, Ihre E-Mail-Adresse oder Ihre IP-Adresse.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Zur einfacheren Verst\u00e4ndlichkeit werden personenbezogene in dieser Datenschutzerkl\u00e4rung nur als \u201e<strong>Daten<\/strong>\u201c bezeichnet.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>2.1 Datenverarbeitung im Zusammenhang mit der Nutzung der Website&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>Die Nutzung unserer Website einschlie\u00dflich des Zugriffs auf die darauf befindlichen \u00f6ffentlich zug\u00e4nglichen Inhalte ist grunds\u00e4tzlich ohne Angabe Ihrer personenbezogenen Daten m\u00f6glich. Erhoben werden lediglich die von Ihrem Internet-Provider mitgeteilten Angaben, darunter insbesondere die Ihnen zugewiesene IP-Adresse, Browsertyp, Internetdienstanbieter (ISP), Ihre Location, Verweis-\/Ausgangsseiten, Betriebssystem, Clickstream-Daten, Zielseite und verweisende URL sowie die Dauer und die Zeit Ihres Besuches. Eine Auswertung erfolgt dabei ausschlie\u00dflich zu statistischen Zwecken unter Wahrung der Anonymit\u00e4t der einzelnen Nutzer.&nbsp;<\/p>\n\n\n\n<p>Die Erhebung dieser Daten erfolgt zur Optimierung unseres Internetauftrittes bzw. zu sicherungsstatistischen Zwecken und daher in unserem berechtigten Interesse nach Art 6 Abs\u202f1 lit f DSGVO. Diese Daten werden f\u00fcr maximal 3 Monate gespeichert.&nbsp;<\/p>\n\n\n\n<p><strong>2.2 Verwendung von Cookies&nbsp;<\/strong><\/p>\n\n\n\n<p>Cookies sind kleine Textbausteine, die von einer Website auf dem Ger\u00e4t des Nutzers abgelegt werden. Viele Cookies enthalten eine sogenannte Cookie-ID. Eine Cookie-ID ist eine eindeutige Kennung des Cookies. Sie besteht aus einer Zeichenfolge, durch welche Websites und Server dem konkreten Internetbrowser zugeordnet werden k\u00f6nnen, in dem das Cookie gespeichert wurde. Dies erm\u00f6glicht es den besuchten Websites und Servern, den individuellen Browser der betroffenen Person von anderen Internetbrowsern, die andere Cookies enthalten, zu unterscheiden. Ein bestimmter Internetbrowser kann \u00fcber die eindeutige Cookie-ID wiedererkannt und identifiziert werden.&nbsp;<\/p>\n\n\n\n<p>Durch den Einsatz von Cookies k\u00f6nnen wir Ihnen nutzerfreundlichere Services bereitstellen, die ohne die Cookie-Setzung nicht m\u00f6glich w\u00e4ren. Mittels eines Cookies k\u00f6nnen die Informationen und Angebote auf der Website im Sinne des Nutzers optimiert werden.&nbsp;<\/p>\n\n\n\n<p>Es werden folgende Kategorien von Cookies unterschieden:&nbsp;<\/p>\n\n\n\n<p><strong>2.2.1. Datenverarbeitung im Zusammenhang mit unbedingt notwendigen Cookies<\/strong>&nbsp;<\/p>\n\n\n\n<p>Diese Cookies sind notwendig, um grundlegende Funktionen der Website sicherzustellen. Wenn Sie unsere Website nutzen, werden von uns automatisch die folgenden Daten erhoben: IP-Adresse, Standort, Browser Plug-in-Typen und -Versionen, Log-In Daten, Betriebssystem und -plattform, Informationen zur Nutzungsdauer. Dies ist erforderlich, um grundlegende Funktionen der Website bereitzustellen sowie um die volle Funktionalit\u00e4t und bestm\u00f6gliche Darstellung der Website auf Ihrem Endger\u00e4t gew\u00e4hrleisten zu k\u00f6nnen. Diese Datenverarbeitungen st\u00fctzen sich daher auf die Rechtsgrundlage Artikel 6 Abs 1 lit f DSGVO (unsere berechtigten Interessen am ordnungsgem\u00e4\u00dfen und voll funktionsf\u00e4higen Betrieb der Website).&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>2.2.2. Datenverarbeitung im Zusammenhang mit Analyse-Cookies &amp; Statistik-Cookies<\/strong>&nbsp;<\/p>\n\n\n\n<p>Analyse-Cookies erlauben es uns, Ihr Nutzungsverhalten zu analysieren. Statistik-Cookies erlauben es uns, Daten zur \u00fcblichen Nutzung unserer Website zu sammeln. Die mit solchen Cookies einhergehenden Datenverarbeitungen dienen dazu, Ihr Nutzerverhalten besser zu verstehen und unser Angebot stetig zu optimieren. Dabei wird \u2013 zus\u00e4tzlich zu den unter Punkt 2 angef\u00fchrten Datenkategorien \u2013 Ihr Nutzerverhalten dokumentiert (z.B. welche Seiten Sie sich wie lange ansehen) und daraus abgeleitet, welche Inhalte Sie interessieren. Au\u00dferdem wird aus dem Verhalten aller Nutzer generell abgeleitet, wie unsere Website genutzt wird, um unser Angebot kontinuierlich verbessern zu k\u00f6nnen.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Der Einsatz von Statistik- und Analyse Cookies erfolgt nur, wenn Sie daf\u00fcr aktiv Ihre Einwilligung gem\u00e4\u00df Artikel 6 Abs 1 lit a DSGVO erteilt haben. Diese Einwilligung ist freiwillig. Einwilligungen k\u00f6nnen Sie stets widerrufen (siehe dazu Punkt 9). Wenn Sie Ihre Einwilligung nicht erteilen, werden keine Statistik- und\/oder Analyse Cookies verwendet (die unbedingt notwendigen Cookies werden unabh\u00e4ngig davon verwendet \u2013 siehe Punkt 2.2.1.).&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;<strong>\u00a7 3&nbsp;<strong><strong>WEITERGABE VON PERSONENBEZOGENEN DATEN<\/strong>&nbsp;<\/strong><\/strong><\/h4>\n\n\n\n<p>Eine \u00dcbermittlung Ihrer pers\u00f6nlichen Daten an Dritte zu anderen als den im Folgenden aufgef\u00fchrten Zwecken findet nicht statt. Wir geben Ihre Daten nur an Dritte weiter, wenn:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sie daf\u00fcr Ihre Einwilligung im Sinne von Artikel 6 Abs 1 lit a DSGVO erteilt haben (Einwilligungen k\u00f6nnen stets widerrufen werden, siehe dazu Punkt 9);&nbsp;<\/li>\n\n\n\n<li>dies nach Artikel 6 Abs 1 lit b DSGVO f\u00fcr die Abwicklung von Vertragsverh\u00e4ltnissen mit Ihnen erforderlich ist;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>f\u00fcr den Fall, dass f\u00fcr die Weitergabe nach Artikel 6 Abs 1 lit c DSGVO eine gesetzliche Verpflichtung besteht oder um einer vollstreckbaren beh\u00f6rdlichen Anordnung zu entsprechen; oder&nbsp;<\/li>\n\n\n\n<li>die Weitergabe nach Artikel 6 Abs 1 lit f DSGVO zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe Ihrer Daten haben.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Manche der oben genannten Empf\u00e4nger k\u00f6nnen sich au\u00dferhalb \u00d6sterreichs befinden oder Ihre personenbezogenen Daten au\u00dferhalb \u00d6sterreichs verarbeiten. Das Datenschutzniveau in anderen L\u00e4ndern entspricht unter Umst\u00e4nden nicht jenem \u00d6sterreichs. Wir setzen daher Ma\u00dfnahmen, um zu gew\u00e4hrleisten, dass alle Empf\u00e4nger ein angemessenes Datenschutzniveau bieten.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 4&nbsp;<strong>LINKS ZU ANDEREN WEBSITES<\/strong><\/strong><\/h4>\n\n\n\n<p>Unsere Website kann an bestimmten Stellen Links zu anderen Websites enthalten, die nicht unserer Kontrolle unterliegen. Die Bereitstellung dieser Links erfolgt lediglich zu Informationszwecken. Wenn Sie auf einen dieser Links klicken, k\u00f6nnen von den Betreibern der jeweiligen Websites Daten \u00fcber Sie erhoben werden. Die Datenverarbeitung k\u00f6nnen erheblich von den hier dargestellten Datenverarbeitungen abweichen (Informationen hierzu k\u00f6nnen Sie auf den Datenschutzerkl\u00e4rungen der jeweiligen Websites abrufen). Wir haben auf diese Datenverarbeitungen keinen Einfluss und \u00fcbernehmen daher keinerlei Verantwortung oder Haftung. Ebenso \u00fcbernehmen wir keinerlei Verantwortung oder Haftung f\u00fcr deren Inhalte.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 5&nbsp;NEWSLETTER<\/strong><\/h4>\n\n\n\n<p>Wenn Sie sich auf unserer Website zu unserem Newsletter anmelden und Ihre Einwilligung gem\u00e4\u00df Artikel 6 Abs 1 lit a DSGVO erteilen, verwenden wir die gesondert von Ihnen mitgeteilten Daten (Name und E-Mail-Adresse), um Ihnen regelm\u00e4\u00dfig unseren E-Mail-Newsletter zuzusenden. Die Abmeldung vom Newsletter (also ein Widerruf der Einwilligung, siehe dazu Punkt 9) ist jederzeit m\u00f6glich und kann entweder durch eine E-Mail an uns (office@mf.ag) oder \u00fcber den daf\u00fcr vorgesehenen Link im Newsletter erfolgen. Nach Widerruf der Einwilligung\/Abmeldung vom Newsletter werden wir Ihnen keinen Newsletter mehr zusenden und l\u00f6schen Ihre Daten aus unserer Empf\u00e4ngerliste.&nbsp;<\/p>\n\n\n\n<p>Zum Newsletterversand setzen wir auf eyepin, einen Dienst der eyepin GmbH, Billrothstra\u00dfe 52, 1190 Wien. Eyepin ist ein Dienst, mit dem u.a. der Versand von Newslettern organisiert und analysiert werden kann. Die von Ihnen zum Zwecke des Newsletterbezugs eingegeben Daten werden auf den Servern von eyepin im europ\u00e4ischen Wirtschaftsraum gespeichert. Wenn Sie keine Analyse durch eyepin wollen, m\u00fcssen Sie den Newsletter abbestellen. Hierf\u00fcr stellen wir in jeder Newsletternachricht einen entsprechenden Link zur Verf\u00fcgung.&nbsp;<\/p>\n\n\n\n<p>Mit Hilfe von eyepin ist es uns m\u00f6glich, unsere Newsletter-Kampagnen zu analysieren. So k\u00f6nnen wir z.B. sehen, ob eine Newsletter-Nachricht ge\u00f6ffnet und welche Links ggf. angeklickt wurden. Auf diese Weise k\u00f6nnen wir u.a. feststellen, welche Links besonders oft angeklickt wurden.&nbsp;<\/p>\n\n\n\n<p>Die Newsletter enthalten sogenannte Z\u00e4hlpixel. Ein Z\u00e4hlpixel ist eine Miniaturgrafik, die in solche E-Mails eingebettet wird, welche im HTML-Format versendet werden, um eine Logdatei-Aufzeichnung und eine Logdatei-Analyse zu erm\u00f6glichen. Dadurch kann eine statistische Auswertung des Erfolges oder Misserfolges von Online-Marketing-Kampagnen durchgef\u00fchrt werden. Solche \u00fcber die in den Newslettern enthaltenen Z\u00e4hlpixel und das Newsletter-Tracking erhobenen personenbezogenen Daten, werden von dem f\u00fcr die Verarbeitung Verantwortlichen gespeichert und ausgewertet, um den Newsletterversand zu optimieren und den Inhalt zuk\u00fcnftiger Newsletter noch besser den Interessen der betroffenen Person anzupassen. Diese personenbezogenen Daten werden nicht an Dritte weitergegeben.&nbsp;<\/p>\n\n\n\n<p>Betroffene Personen sind jederzeit berechtigt, die diesbez\u00fcgliche gesonderte, \u00fcber das Double-Opt-In-Verfahren abgegebene Einwilligungserkl\u00e4rung \u00fcber die Abmeldung vom Erhalt des Newsletters zu widerrufen. Nach einem Widerruf werden keinerlei weitere Daten erhoben und die Adresse wird auf eine Sperrliste gesetzt, um die Abmeldung zu dokumentieren und weitere Zusendungen zu verhindern.&nbsp;<\/p>\n\n\n\n<p>Ausf\u00fchrliche Informationen zu den Funktionen von eyepin entnehmen Sie folgendem Link: <a href=\"https:\/\/www.eyepin.com\/de\/e-mail-newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.eyepin.com\/de\/e-mail-newsletter<\/a>.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 6&nbsp;<strong>KONTAKTANFRAGEN<\/strong><\/strong><\/h4>\n\n\n\n<p>Sofern Sie per Telefon, E-Mail oder Kontaktformular mit uns in Kontakt treten, werden die dabei von Ihnen angegebenen Daten zur Bearbeitung Ihrer Anfrage genutzt. Die Verarbeitung erfolgt auf Basis des berechtigten Interesses gem\u00e4\u00df Art 6 Abs 1 lit f DSGVO; unser berechtigtes Interesse besteht in der sachgerechten Beantwortung von Kundenanfragen; zielt die Anfrage auf den Abschluss eines Vertrages ab, so kann die Verarbeitung zudem auf die Rechtsgrundlage nach Art 6 Abs 1 lit b DSGVO gest\u00fctzt werden. Ihre Daten werden gel\u00f6scht, sofern Ihre Anfrage abschlie\u00dfend beantwortet worden ist und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen, wie bspw. bei einer sich etwaig anschlie\u00dfenden Vertragsabwicklung.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 7&nbsp;<strong>DAUER DER SPEICHERUNG<\/strong><\/strong><\/h4>\n\n\n\n<p>Wir speichern Ihre personenbezogenen Daten nur solange, wie es zur Erreichung der oben genannten Zwecke erforderlich ist oder gesetzlich vorgeschrieben ist. Wir l\u00f6schen Ihre Daten innerhalb der gesetzlichen L\u00f6schfristen und demnach in der Regel nach maximal sieben Jahren (steuerliche Aufbewahrungsfrist). Au\u00dferdem k\u00f6nnten Daten innerhalb der gesetzlichen L\u00f6schfristen als Beweise f\u00fcr allf\u00e4llige Rechtsstreitigkeiten aufbewahrt werden. Die Datenaufbewahrung st\u00fctzt sich somit entweder auf der Rechtsgrundlage Artikel 6 Abs 1 lit c DSGVO (wenn die Verarbeitung zur Erf\u00fcllung einer rechtlichen oder gesetzlichen Verpflichtung erforderlich ist, der wir unterliegen) oder auf der Rechtsgrundlage Artikel 6 Abs 1 lit f DSGVO (wenn die Verarbeitung zur Wahrung unserer berechtigten Interessen erforderlich ist; zB als Beweise f\u00fcr Rechtsstreitigkeiten).&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 8&nbsp;<strong>DATENSICHERHEIT<\/strong><\/strong><\/h4>\n\n\n\n<p>Der Schutz Ihrer Daten ist uns ein wichtiges Anliegen. Daher nutzen wir geeignete Sicherheitsma\u00dfnahmen, um die von uns verarbeiteten Daten gegen unbefugten Zugriff, unbefugte Erhebung, Nutzung, Ver\u00f6ffentlichung, Vervielf\u00e4ltigung, \u00c4nderung oder L\u00f6schung zu sch\u00fctzen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 9&nbsp;BETROFFENENRECHTE<\/strong><\/h4>\n\n\n\n<p>Werden personenbezogene Daten von Ihnen verarbeitet, sind Sie ein \u201eBetroffener\u201c im Sinne der DSGVO. Ihnen stehen folgende Rechte gegen\u00fcber uns als Verantwortlichen zu:&nbsp;<\/p>\n\n\n\n<p><strong>Recht auf Auskunft<\/strong>: Sie k\u00f6nnen Auskunft dar\u00fcber verlangen, ob wir personenbezogene Daten von Ihnen verarbeiten. Ist dies der Fall, so haben Sie ein Recht auf Auskunft \u00fcber diese personenbezogenen Daten sowie auf weitere mit der Verarbeitung zusammenh\u00e4ngende Informationen (Art 15 DSGVO). Bitte beachten Sie, dass dieses Auskunftsrecht in bestimmten F\u00e4llen eingeschr\u00e4nkt oder ausgeschlossen sein kann.&nbsp;<\/p>\n\n\n\n<p><strong>Recht auf Berichtigung<\/strong>: F\u00fcr den Fall, dass personenbezogene Daten \u00fcber Sie nicht (mehr) zutreffend oder unvollst\u00e4ndig sind, k\u00f6nnen Sie eine Berichtigung und gegebenenfalls Vervollst\u00e4ndigung dieser Daten verlangen (Art16 DSGVO).&nbsp;<\/p>\n\n\n\n<p><strong>Recht auf L\u00f6schung oder Einschr\u00e4nkung der Verarbeitung<\/strong>: Bei Vorliegen der gesetzlichen Voraussetzungen k\u00f6nnen Sie die L\u00f6schung Ihrer personenbezogenen Daten (Art 17 DSGVO) oder die Einschr\u00e4nkung der Verarbeitung dieser Daten (Art 18 DSGVO) verlangen. Das Recht auf L\u00f6schung nach Art 17 Abs 1 und 2 DSGVO besteht jedoch unter anderem dann nicht, wenn die Verarbeitung personenbezogener Daten zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich ist (Art 17 Abs 3 lit b DSGVO). In einem solchen Fall werden wir Sie dahingehend benachrichtigen.&nbsp;<\/p>\n\n\n\n<p><strong>Widerspruchsrecht<\/strong>: Aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, k\u00f6nnen Sie der Verarbeitung Sie betreffender personenbezogener Daten durch uns zudem jederzeit widersprechen (Art 21 DSGVO). Sofern die gesetzlichen Voraussetzungen vorliegen, verarbeiten wir in der Folge Ihre personenbezogenen Daten nicht mehr (siehe dazu im Detail weiter unten).&nbsp;<\/p>\n\n\n\n<p><strong>Recht auf Daten\u00fcbertragbarkeit<\/strong>: Sie sind berechtigt, unter den Voraussetzungen von Art 20 DSGVO von uns zu verlangen, dass wir Ihnen die Sie betreffenden personenbezogenen Daten, die Sie uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu \u00fcbergeben.&nbsp;<\/p>\n\n\n\n<p><strong>Widerrufsrecht<\/strong>: Sie haben das Recht, Ihre Einwilligung jederzeit zu widerrufen. Der Widerruf wirkt erst f\u00fcr die Zukunft; das hei\u00dft, durch den Widerruf wird die Rechtm\u00e4\u00dfigkeit, der aufgrund der Einwilligung bis zum Widerruf erfolgten Verarbeitungen nicht ber\u00fchrt.&nbsp;<\/p>\n\n\n\n<p><strong>Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde<\/strong>: Unbeschadet eines anderweitigen verwaltungsrechtlichen oder gerichtlichen Rechtsbehelfes steht Ihnen das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde \u2013 insbesondere in dem Mitgliedsstaat Ihres Aufenthaltsortes \u2013 zu, wenn Sie der Ansicht sind, dass die Verarbeitung Ihrer personenbezogenen Daten durch uns gegen die DSGVO verst\u00f6\u00dft.&nbsp;<\/p>\n\n\n\n<p><strong>Die f\u00fcr uns zust\u00e4ndige Aufsichtsbeh\u00f6rde ist<\/strong>:<br>\u00d6sterreichische Datenschutzbeh\u00f6rde&nbsp;<br>Barichgasse 40-42&nbsp;&nbsp;&nbsp;<br>1030 Wien&nbsp;<br>Telefon: +43 1 52 152-0&nbsp;<br>E-Mail: <a href=\"mailto:dsb@dsb.gv.at\" target=\"_blank\" rel=\"noreferrer noopener\">dsb@dsb.gv.at<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p>Die Website der Datenschutzbeh\u00f6rde ist unter folgendem Link abrufbar: <a href=\"https:\/\/www.dsb.gv.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dsb.gv.at<\/a>.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Wir empfehlen Ihnen allerdings, eine Beschwerde zun\u00e4chst immer an unseren Datenschutzbeauftragten zu richten.<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Ihre Antr\u00e4ge \u00fcber die Aus\u00fcbung Ihrer Rechte sollten nach M\u00f6glichkeit schriftlich an die unter Punkt 1 angegebene Anschrift adressiert werden.<\/strong>&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00a7 10&nbsp;\u00c4NDERUNG DIESER DATENSCHUTZERKL\u00c4RUNG<\/strong><\/h4>\n\n\n\n<p>Unsere Datenschutzerkl\u00e4rung wird in gewissen Zeitabst\u00e4nden aktualisiert. Die aktuelle Fassung unserer Datenschutzerkl\u00e4rung ist stets auf unserer Website abrufbar.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vielen Dank f\u00fcr Ihren Besuch auf unserer Webseite und f\u00fcr Ihr Interesse an unseren Dienstleistungen. Der Schutz Ihrer personenbezogenen Daten ist uns ein wichtiges Anliegen. Wir verarbeiten Ihre personenbezogenen Daten ausschlie\u00dflich im Rahmen des geltenden Datenschutzrechts; dies umfasst insbesondere die Bestimmungen der EU-Datenschutz-Grundverordnung (im Folgenden: \u201eDSGVO\u201c) sowie des \u00f6sterreichischen Datenschutzgesetzes (im Folgenden \u201eDSG\u201c). Nachfolgend m\u00f6chten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-53724","page","type-page","status-publish","hentry"],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","gform-image-choice-sm":"","gform-image-choice-md":"","gform-image-choice-lg":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Vielen Dank f\u00fcr Ihren Besuch auf unserer Webseite und f\u00fcr Ihr Interesse an unseren Dienstleistungen. Der Schutz Ihrer personenbezogenen Daten ist uns ein wichtiges Anliegen. Wir verarbeiten Ihre personenbezogenen Daten ausschlie\u00dflich im Rahmen des geltenden Datenschutzrechts; dies umfasst insbesondere die Bestimmungen der EU-Datenschutz-Grundverordnung (im Folgenden: \u201eDSGVO\u201c) sowie des \u00f6sterreichischen Datenschutzgesetzes (im Folgenden \u201eDSG\u201c). Nachfolgend m\u00f6chten wir Sie dar\u00fcber informieren, welche personenbezogenen Daten wir erheben und wie wir sie verarbeiten.&nbsp; \u00a7 1&nbsp;VERANTWORTLICHER&nbsp;&nbsp; Verantwortlicher f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten ist:&nbsp;Management Factory Corporate Advisory GmbH&nbsp;&nbsp;Lothringerstr. 14&nbsp;&nbsp;1030 Wien&nbsp;\u00d6STERREICHE-Mail: office@mf.ag&nbsp; (im Folgenden auch \u201eManagement Factory\u201c, \u201ewir\u201c, \u201euns\u201c, \u201eunser\u201c genannt).&nbsp; Kontaktdaten unseres Datenschutzbeauftragten: Mag. Christian&hellip;<\/p>\n","category_list_v2":"","author_info_v2":{"name":"Pierre","url":"https:\/\/mf.ag\/de\/author\/superfun\/"},"comments_num_v2":"0 comments","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung &#187; Management Factory<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mf.ag\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung\" \/>\n<meta property=\"og:description\" content=\"Vielen Dank f\u00fcr Ihren Besuch auf unserer Webseite und f\u00fcr Ihr Interesse an unseren Dienstleistungen. Der Schutz Ihrer personenbezogenen Daten ist uns ein wichtiges Anliegen. Wir verarbeiten Ihre personenbezogenen Daten ausschlie\u00dflich im Rahmen des geltenden Datenschutzrechts; dies umfasst insbesondere die Bestimmungen der EU-Datenschutz-Grundverordnung (im Folgenden: \u201eDSGVO\u201c) sowie des \u00f6sterreichischen Datenschutzgesetzes (im Folgenden \u201eDSG\u201c). Nachfolgend m\u00f6chten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mf.ag\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Management Factory\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T11:40:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/mf.ag\\\/de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung &#187; Management Factory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#website\"},\"datePublished\":\"2023-09-12T08:04:56+00:00\",\"dateModified\":\"2024-07-15T11:40:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mf.ag\\\/de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mf.ag\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mf.ag\\\/de\\\/\",\"name\":\"VALTUS Management Factory\",\"description\":\"Mit Executive Interim Management und Financial Advisory das Gesch\u00e4ft voranbringen\",\"publisher\":{\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mf.ag\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#organization\",\"name\":\"VALTUS Management Factory\",\"url\":\"https:\\\/\\\/mf.ag\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"VALTUS Management Factory\"},\"image\":{\"@id\":\"https:\\\/\\\/mf.ag\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung &#187; Management Factory","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung","og_description":"Vielen Dank f\u00fcr Ihren Besuch auf unserer Webseite und f\u00fcr Ihr Interesse an unseren Dienstleistungen. Der Schutz Ihrer personenbezogenen Daten ist uns ein wichtiges Anliegen. Wir verarbeiten Ihre personenbezogenen Daten ausschlie\u00dflich im Rahmen des geltenden Datenschutzrechts; dies umfasst insbesondere die Bestimmungen der EU-Datenschutz-Grundverordnung (im Folgenden: \u201eDSGVO\u201c) sowie des \u00f6sterreichischen Datenschutzgesetzes (im Folgenden \u201eDSG\u201c). Nachfolgend m\u00f6chten [&hellip;]","og_url":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/","og_site_name":"Management Factory","article_modified_time":"2024-07-15T11:40:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/","url":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung &#187; Management Factory","isPartOf":{"@id":"https:\/\/mf.ag\/de\/#website"},"datePublished":"2023-09-12T08:04:56+00:00","dateModified":"2024-07-15T11:40:58+00:00","breadcrumb":{"@id":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mf.ag\/de\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mf.ag\/de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mf.ag\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/mf.ag\/de\/#website","url":"https:\/\/mf.ag\/de\/","name":"VALTUS Management Factory","description":"Mit Executive Interim Management und Financial Advisory das Gesch\u00e4ft voranbringen","publisher":{"@id":"https:\/\/mf.ag\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mf.ag\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mf.ag\/de\/#organization","name":"VALTUS Management Factory","url":"https:\/\/mf.ag\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mf.ag\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"VALTUS Management Factory"},"image":{"@id":"https:\/\/mf.ag\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/pages\/53724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/comments?post=53724"}],"version-history":[{"count":4,"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/pages\/53724\/revisions"}],"predecessor-version":[{"id":56964,"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/pages\/53724\/revisions\/56964"}],"wp:attachment":[{"href":"https:\/\/mf.ag\/de\/wp-json\/wp\/v2\/media?parent=53724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}